{"id":2255,"date":"2024-05-22T18:40:54","date_gmt":"2024-05-22T17:40:54","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=2255"},"modified":"2024-05-22T18:40:54","modified_gmt":"2024-05-22T17:40:54","slug":"securite-alimentaire-orienter-lagriculture-africaine-dans-une-logique-forestiere-et-agro-ecologique","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/05\/22\/securite-alimentaire-orienter-lagriculture-africaine-dans-une-logique-forestiere-et-agro-ecologique\/","title":{"rendered":"S\u00e9curit\u00e9 alimentaire: orienter l&rsquo;agriculture africaine dans une logique foresti\u00e8re et agro-\u00e9cologique"},"content":{"rendered":"<p>Des experts et universitaires africains, participants aux travaux de la premi\u00e8re Conf\u00e9rence panafricaine sur le d\u00e9bat alimentaire (The Panafrican Food debate-Algiers Edition), ont pr\u00e9conis\u00e9 \u00e0 Alger d&rsquo;orienter l&rsquo;agriculture africaine dans une logique foresti\u00e8re et agro-\u00e9cologique.<\/p>\n<p>Dans \u00ab\u00a0la D\u00e9claration d&rsquo;Alger sur le d\u00e9bat alimentaire africain\u00a0\u00bb, qu&rsquo;ils ont adopt\u00e9e mardi en fin de journ\u00e9e, \u00e0 l&rsquo;issue de la conf\u00e9rence, les experts ont appel\u00e9 \u00e0 \u00a0\u00bborienter l&rsquo;agriculture africaine dans une logique foresti\u00e8re et agro-\u00e9cologique, s&rsquo;inspirant de l&rsquo;organisation oasienne afin de densifier l&rsquo;effort de convergence des fili\u00e8res animales et v\u00e9g\u00e9tales dans la perspective d&rsquo;un d\u00e9veloppement rural durable\u00a0\u00bb.<\/p>\n<p>Ils ont, dans ce sens, relev\u00e9 que \u00a0\u00bbl&rsquo;agriculture du futur en Afrique sera celle des synergies des connaissances codifi\u00e9es, d\u00e9tenues par les organismes de formation et de recherches avec celles dites tacites, d\u00e9tenues par des millions d&rsquo;agriculteurs et d&rsquo;\u00e9leveurs africains\u00a0\u00bb.<\/p>\n<p>Les participants au d\u00e9bat africain ont \u00e9galement soulign\u00e9 que la r\u00e9solution de la question alimentaire est une activit\u00e9 complexe qui \u00ab\u00a0n\u00e9cessite la mise en \u0153uvre trans-g\u00e9n\u00e9rationnelle de ressources transversales multiples et vari\u00e9es\u00a0\u00bb, saluant dans ce contexte \u00a0\u00bbl&rsquo;engagement des jeunesses africaines paysannes inventives dans leurs efforts continus afin de relever les d\u00e9fis alimentaires de toutes natures\u00a0\u00bb.<\/p>\n<p>La D\u00e9claration d&rsquo;Alger sur le d\u00e9bat alimentaire africain a, en outre, salu\u00e9 la d\u00e9cision de poursuive la conf\u00e9rence panafricaine sur la question alimentaire \u00e0 Dakar au S\u00e9n\u00e9gal \u00e0 la fin de cette ann\u00e9e, pour une seconde \u00e9dition afin d&rsquo;approfondir et d&rsquo;\u00e9largir les d\u00e9bats \u00e0 d&rsquo;autres participants africains.<\/p>\n<p>Organis\u00e9e dans le cadre de la 22e \u00e9dition du Salon international de l&rsquo;agriculture de l&rsquo;\u00e9levage et de l&rsquo;Agro-industrie \u00ab\u00a0SIPSA-FILAHA\u00a0\u00bb (20 au 23 mai courant), la premi\u00e8re Conf\u00e9rence panafricaine sur le d\u00e9bat alimentaire a vu la participation de plusieurs d\u00e9l\u00e9gations de pays africains, notamment du Burkina Faso, Mali, S\u00e9n\u00e9gal, Mauritanie, Niger, R\u00e9publique arabe sahraouie d\u00e9mocratique (RASD) et C\u00f4te d&rsquo;Ivoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des experts et universitaires africains, participants aux travaux de la premi\u00e8re Conf\u00e9rence panafricaine sur le d\u00e9bat alimentaire (The Panafrican Food debate-Algiers Edition), ont pr\u00e9conis\u00e9 \u00e0 <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/05\/22\/securite-alimentaire-orienter-lagriculture-africaine-dans-une-logique-forestiere-et-agro-ecologique\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":2256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[256,200],"tags":[],"class_list":["post-2255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agriculture","category-economie"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=2255"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2255\/revisions"}],"predecessor-version":[{"id":2257,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2255\/revisions\/2257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/2256"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=2255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=2255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=2255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}