{"id":2278,"date":"2024-05-24T17:36:21","date_gmt":"2024-05-24T16:36:21","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=2278"},"modified":"2024-05-24T17:36:21","modified_gmt":"2024-05-24T16:36:21","slug":"traduction-de-la-vision-strategique-du-president-tebboune-creation-dun-grand-groupe-public-de-construction-ferroviaire","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/05\/24\/traduction-de-la-vision-strategique-du-president-tebboune-creation-dun-grand-groupe-public-de-construction-ferroviaire\/","title":{"rendered":"Traduction de la Vision strat\u00e9gique du Pr\u00e9sident Tebboune : Cr\u00e9ation d&rsquo;un grand groupe public de construction ferroviaire."},"content":{"rendered":"<p>S\u2019inscrivant dans la vision strat\u00e9gique \u00e9conomique du Pr\u00e9sident de la R\u00e9publique M. Abdelmadjid Tebboune et en application de ses directives, le Conseil de Participation de l\u2019Etat (CPE) qui vient de tenir, sous la pr\u00e9sidence du Premier Ministre Nadir Larbaoui, sa 184e session, ce jeudi 23 mai 2024, a act\u00e9 la cr\u00e9ation d\u2019un grand groupe public d\u00e9di\u00e9 \u00e0 l\u2019ing\u00e9nierie et \u00e0 la r\u00e9alisation des projets ferroviaires, \u00e0 travers la reconfiguration du secteur public des infrastructures ferroviaires.<\/p>\n<p>L\u2019approche retenue vise \u00e0 mettre \u00e0 profit l\u2019important programme ferroviaire d\u00e9cid\u00e9 \u060c pour mettre en synergie les capacit\u00e9s d\u2019ing\u00e9nierie et de r\u00e9alisation des entreprises publiques sp\u00e9cialis\u00e9es dans le domaine de la construction ferroviaire, dans le cadre d\u2019un regroupement coh\u00e9rent de leurs capacit\u00e9s et de leur savoir-faire.<\/p>\n<p>Dans ce cadre, le mod\u00e8le organisationnel projet\u00e9 est ax\u00e9 sur la constitution d\u2019un grand Groupe form\u00e9 par une soci\u00e9t\u00e9 m\u00e8re EPE\/SPA, \u00e0 laquelle sont rattach\u00e9es quatre (04) filiales sp\u00e9cialis\u00e9es dans le ferroviaire \u00e0 savoir, les entreprises publiques \u00e9conomiques suivantes : Setirail Spa, sp\u00e9cialis\u00e9e dans l\u2019ing\u00e9nierie ferroviaire ( \u00e9tudes et suivi des travaux) Infrarail Spa, sp\u00e9cialis\u00e9e dans les travaux d\u2019infrastructures ferroviaires, Railelect Spa, sp\u00e9cialis\u00e9e dans l\u2019\u00e9lectrification ferroviaire et Infrafer Spa en charge des infrastructures et de production d\u2019agr\u00e9gats.<\/p>\n<p>Ainsi, notre pays sera dot\u00e9e d\u2019une entit\u00e9 d\u2019envergue, d\u2019ing\u00e9nierie et de r\u00e9alisation dans le domaine ferroviaire, \u00e0 m\u00eame de r\u00e9pondre aux grands projets ferroviaires structurants, d\u00e9cid\u00e9s par Monsieur le Pr\u00e9sident de la R\u00e9publique dans l\u2019optique d\u2019un maillage ferroviaire du territoire, par la densification du r\u00e9seau, ce qui qui requiert une mobilisation cons\u00e9quente des capacit\u00e9s nationales d\u2019ing\u00e9nierie et de r\u00e9alisation.<\/p>\n<p>La cr\u00e9ation de ce groupe vise, dans le cadre d\u2019une vision strat\u00e9gique, \u00e0 :<\/p>\n<p>-Conforter l\u2019autonomie technologique du pays ;<\/p>\n<p>-renforcer la position des entreprises nationales face \u00e0 la rude concurrence \u00e9trang\u00e8re, en augmentant les capacit\u00e9s de n\u00e9gociation face ou avec les groupes \u00e9trangers ;<\/p>\n<p>-am\u00e9liorer la maitrise du management, par une mutualisation des ressources et une \u00e9conomie d\u2019\u00e9chelle, notamment, en mati\u00e8re d\u2019approvisionnement ;<\/p>\n<p>-enfin, induire des effets d\u2019entra\u00eenement sur les entreprises nationales hors portefeuille, notamment les sous-traitantes, en amont et en aval de la cha\u00eene de valeur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u2019inscrivant dans la vision strat\u00e9gique \u00e9conomique du Pr\u00e9sident de la R\u00e9publique M. Abdelmadjid Tebboune et en application de ses directives, le Conseil de Participation de <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/05\/24\/traduction-de-la-vision-strategique-du-president-tebboune-creation-dun-grand-groupe-public-de-construction-ferroviaire\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":2161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[198],"tags":[],"class_list":["post-2278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=2278"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2278\/revisions"}],"predecessor-version":[{"id":2279,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2278\/revisions\/2279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/2161"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=2278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=2278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=2278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}