{"id":2948,"date":"2024-07-05T19:12:01","date_gmt":"2024-07-05T18:12:01","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=2948"},"modified":"2024-07-05T19:12:01","modified_gmt":"2024-07-05T18:12:01","slug":"pour-la-9e-fois-de-son-histoire-le-cr-belouizdad-remporte-la-coupe-dalgerie","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/07\/05\/pour-la-9e-fois-de-son-histoire-le-cr-belouizdad-remporte-la-coupe-dalgerie\/","title":{"rendered":"Pour la 9e fois de son histoire&#8230; le CR Belouizdad remporte la Coupe d&rsquo;Alg\u00e9rie"},"content":{"rendered":"<p>Le CR Belouizdad a battu ce soir son voisin, le MC Alger, sur le score d&rsquo;un but \u00e0 z\u00e9ro, lors de la finale de la Coupe d&rsquo;Alg\u00e9rie, remportant ainsi la neuvi\u00e8me coupe de son histoire.<\/p>\n<p>Le CRB a ouvert le score \u00e0 la 42e minute de la premi\u00e8re mi-temps gr\u00e2ce \u00e0 une t\u00eate pr\u00e9cise de Chouaib Keddad qui a trouv\u00e9 les filets du gardien Ramadhan.<\/p>\n<p>En deuxi\u00e8me mi-temps, les co\u00e9quipiers de Youcef Bela\u00efli n&rsquo;ont pas r\u00e9ussi \u00e0 \u00e9galiser, malgr\u00e9 une d\u00e9fense solide des joueurs du CR Belouizdad tout au long du match.<\/p>\n<p>La star du milieu de terrain du MCA, \u00ab\u00a0Zougrana\u00a0\u00bb, a \u00e9galement rat\u00e9 une occasion d&rsquo;\u00e9galiser apr\u00e8s avoir dribbl\u00e9 plusieurs joueurs et s&rsquo;\u00eatre retrouv\u00e9 face au gardien Gendouz, mais sa frappe a fr\u00f4l\u00e9 le poteau droit du but.<\/p>\n<p>De leur c\u00f4t\u00e9, les prot\u00e9g\u00e9s de l&rsquo;entra\u00eeneur Paqueta ont manqu\u00e9 l&rsquo;occasion d&rsquo;aggraver le score lorsque la frappe de Ben Ghaith a heurt\u00e9 le poteau gauche du gardien du MC Alger.<\/p>\n<p>Le CR Belouizdad a continu\u00e9 de cr\u00e9er des opportunit\u00e9s, notamment \u00e0 la 87e minute, lorsque la t\u00eate du d\u00e9fenseur Khacef a touch\u00e9 le poteau gauche du gardien Ramadhan.<\/p>\n<p>Avec ce sacre, les \u00ab\u00a0Enfants d&rsquo;El-Aqiba\u00a0\u00bb ont priv\u00e9 les \u00ab\u00a0Chnaoua\u00a0\u00bb de r\u00e9aliser le doubl\u00e9, ces derniers ayant remport\u00e9 le championnat cette saison. R.S<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le CR Belouizdad a battu ce soir son voisin, le MC Alger, sur le score d&rsquo;un but \u00e0 z\u00e9ro, lors de la finale de la <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/07\/05\/pour-la-9e-fois-de-son-histoire-le-cr-belouizdad-remporte-la-coupe-dalgerie\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":2949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[258,7],"tags":[],"class_list":["post-2948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-sports"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=2948"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2948\/revisions"}],"predecessor-version":[{"id":2950,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/2948\/revisions\/2950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/2949"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=2948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=2948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=2948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}