{"id":3065,"date":"2024-07-09T20:26:36","date_gmt":"2024-07-09T19:26:36","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=3065"},"modified":"2024-07-09T20:28:04","modified_gmt":"2024-07-09T19:28:04","slug":"la-communaute-algerienne-celebre-le-62e-anniversaire-de-lindependance-a-washington-video","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/07\/09\/la-communaute-algerienne-celebre-le-62e-anniversaire-de-lindependance-a-washington-video\/","title":{"rendered":"La communaut\u00e9 alg\u00e9rienne c\u00e9l\u00e8bre le 62e anniversaire de l&rsquo;ind\u00e9pendance \u00e0 Washington ( Video)"},"content":{"rendered":"<p>Le 7 juillet 2024, l&rsquo;Association alg\u00e9ro-am\u00e9ricaine de Washington a organis\u00e9 une grande c\u00e9l\u00e9bration \u00e0 l&rsquo;occasion du 62e anniversaire de l&rsquo;ind\u00e9pendance de l&rsquo;Alg\u00e9rie. L&rsquo;\u00e9v\u00e9nement s&rsquo;est tenu \u00e0 Alexandria, en Virginie, dans une ambiance festive empreinte de fiert\u00e9 et de dignit\u00e9.<br \/>\nLa c\u00e9r\u00e9monie a attir\u00e9 un public distingu\u00e9, comprenant des diplomates, des personnalit\u00e9s publiques, des membres de la communaut\u00e9 alg\u00e9rienne ainsi que des citoyens am\u00e9ricains. Mohammed Salah Ben Ammar, pr\u00e9sident de l&rsquo;Association alg\u00e9ro-am\u00e9ricaine, a ouvert les festivit\u00e9s en soulignant l&rsquo;importance des relations historiques entre l&rsquo;Alg\u00e9rie et les \u00c9tats-Unis, et en mettant en lumi\u00e8re le r\u00f4le crucial de la diaspora alg\u00e9rienne dans la r\u00e9gion de Washington, en Virginie et aux \u00c9tats-Unis en g\u00e9n\u00e9ral.<br \/>\nL&rsquo;ambassadeur d&rsquo;Alg\u00e9rie aux \u00c9tats-Unis, Sabri Boukadoum, a prononc\u00e9 un discours \u00e9mouvant, \u00e9voquant l&rsquo;h\u00e9ro\u00efsme de l&rsquo;Alg\u00e9rie et l&rsquo;histoire partag\u00e9e avec les \u00c9tats-Unis, tout en insistant sur les liens solides qui unissent les deux nations.<br \/>\nParmi les invit\u00e9s de marque, Kathy Karmz, directrice de la Fondation Emir Abdelkader, venue de l&rsquo;Iowa, a mis en avant les exploits de l&rsquo;Emir Abdelkader et son r\u00f4le historique important. John Kaiser, \u00e9galement de la Fondation et auteur d&rsquo;un ouvrage sur l&rsquo;Emir intitul\u00e9 \u00ab\u00a0The Commander of the Faithful\u00a0\u00bb, a abord\u00e9 l&rsquo;h\u00e9ritage de l&rsquo;Emir et son impact profond sur l&rsquo;histoire alg\u00e9rienne.<br \/>\nMustapha Boudjerada, fondateur de Dar al-Iman, a pr\u00e9sent\u00e9 les activit\u00e9s de la mosqu\u00e9e alg\u00e9rienne de Lorton et ses diverses initiatives.<br \/>\nL&rsquo;\u00e9v\u00e9nement a \u00e9galement propos\u00e9 une exposition de v\u00eatements et de traditions alg\u00e9riennes, offrant aux participants l&rsquo;opportunit\u00e9 de d\u00e9couvrir la richesse et la diversit\u00e9 de la culture alg\u00e9rienne. Des vid\u00e9os promotionnelles mettant en valeur la beaut\u00e9 et la diversit\u00e9 g\u00e9ographique et linguistique de l&rsquo;Alg\u00e9rie ont \u00e9t\u00e9 projet\u00e9es.<br \/>\nL&rsquo;artiste Yacine, venu de New York, a apport\u00e9 une touche musicale \u00e0 la c\u00e9l\u00e9bration, accompagn\u00e9 de divers groupes am\u00e9ricains qui ont su cr\u00e9er une atmosph\u00e8re joyeuse et festive.<br \/>\nCette manifestation, organis\u00e9e pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive, a \u00e9t\u00e9 unanimement salu\u00e9e par les participants. Elle a renforc\u00e9 les liens culturels entre l&rsquo;Alg\u00e9rie et les \u00c9tats-Unis, et tous ont soulign\u00e9 l&rsquo;importance de p\u00e9renniser cet \u00e9v\u00e9nement annuel, reconnaissant son r\u00f4le majeur dans le renforcement des relations entre les deux pays amis et dans la promotion de la culture alg\u00e9rienne aupr\u00e8s de la soci\u00e9t\u00e9 am\u00e9ricaine. R.I<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/450052872_465702366212320_1876765194647147746_n-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-3070\" srcset=\"https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/450052872_465702366212320_1876765194647147746_n-300x300.jpeg 300w, https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/450052872_465702366212320_1876765194647147746_n-1024x1024.jpeg 1024w, https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/450052872_465702366212320_1876765194647147746_n-150x150.jpeg 150w, https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/450052872_465702366212320_1876765194647147746_n-768x768.jpeg 768w, https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/450052872_465702366212320_1876765194647147746_n.jpeg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-3065-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/ahtfalat_alyd_alwtny_fy_washntn.mp4?_=1\" \/><a href=\"https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/ahtfalat_alyd_alwtny_fy_washntn.mp4\">https:\/\/capalgerie.dz\/wp-content\/uploads\/2024\/07\/ahtfalat_alyd_alwtny_fy_washntn.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le 7 juillet 2024, l&rsquo;Association alg\u00e9ro-am\u00e9ricaine de Washington a organis\u00e9 une grande c\u00e9l\u00e9bration \u00e0 l&rsquo;occasion du 62e anniversaire de l&rsquo;ind\u00e9pendance de l&rsquo;Alg\u00e9rie. L&rsquo;\u00e9v\u00e9nement s&rsquo;est tenu <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/07\/09\/la-communaute-algerienne-celebre-le-62e-anniversaire-de-lindependance-a-washington-video\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":3067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[258,198,202],"tags":[],"class_list":["post-3065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-actualite","category-monde"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/3065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=3065"}],"version-history":[{"count":3,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/3065\/revisions"}],"predecessor-version":[{"id":3071,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/3065\/revisions\/3071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/3067"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=3065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=3065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=3065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}