{"id":3742,"date":"2024-07-25T16:50:28","date_gmt":"2024-07-25T15:50:28","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=3742"},"modified":"2024-07-25T16:50:28","modified_gmt":"2024-07-25T15:50:28","slug":"le-projet-de-la-station-de-dessalement-de-leau-de-mer-de-cap-blanc-sera-livre-dans-les-delais-impartis","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/07\/25\/le-projet-de-la-station-de-dessalement-de-leau-de-mer-de-cap-blanc-sera-livre-dans-les-delais-impartis\/","title":{"rendered":"Le projet de la station de dessalement de l&rsquo;eau de mer de Cap Blanc sera livr\u00e9 dans les d\u00e9lais impartis"},"content":{"rendered":"<p>Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi a affirm\u00e9, jeudi \u00e0 Oran, que le projet de r\u00e9alisation de la station de dessalement de l&rsquo;eau de mer de Cap Blanc, \u00e0 l&rsquo;Ouest de la wilaya d&rsquo;Oran, sera livr\u00e9 dans ses d\u00e9lais impartis et la phase de r\u00e9ception et d&rsquo;installation des \u00e9quipements sera lanc\u00e9e prochainement. Dans une d\u00e9claration \u00e0 la presse en marge de sa visite de terrain au site du projet, M. Hachichi a soulign\u00e9 que les travaux de la r\u00e9alisation de la station de dessalement de l&rsquo;eau de mer de Cap Blanc ont atteint environ 70% et les 30% restants sont r\u00e9serv\u00e9s \u00e0 la r\u00e9ception et \u00e0 l&rsquo;installation des \u00e9quipements. Le m\u00eame responsable a rappel\u00e9 l&rsquo;importance de ce projet strat\u00e9gique, d\u00e9cid\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, dans le cadre du programme d&rsquo;urgence pour s\u00e9curiser l&rsquo;alimentation en eau potable, sachant que la capacit\u00e9 de production de cette station est de 300.000 m3 d&rsquo;eau dessal\u00e9e\/jour, permettant d&rsquo;alimenter pas moins de 3 millions d&rsquo;habitants en eau potable. M. Hachichi a estim\u00e9 que la phase prochaine est consid\u00e9r\u00e9e comme \u00ab\u00a0d\u00e9cisive\u00a0\u00bb et a donn\u00e9 des instructions pour fournir tous les efforts n\u00e9cessaires pour lever les obstacles qui entravent l&rsquo;avancement du projet, notamment ceux li\u00e9s \u00e0 la r\u00e9ception d&rsquo;\u00e9quipements. Pour sa part, le wali d&rsquo;Oran, Sa\u00efd Sayoud, a soulign\u00e9 que les travaux de r\u00e9alisation du r\u00e9seau de canalisations qui transporteront les eaux dessal\u00e9es de la station de Cap Blanc enregistrent un avancement important, affirmant que le projet sera livr\u00e9 vers la fin du mois de septembre prochain. Les canalisations sont en cours de r\u00e9alisation sur une distance de 50 km en direction de la commune de Boutlelis, \u00e0 l&rsquo;Ouest, et les communes de A\u00efn El-Turck et Mers El-Kebir, \u00e0 l&rsquo;Est, outre deux r\u00e9servoirs d&rsquo;une capacit\u00e9 de 50.000 m3 pour le premier et 30.000 m3 pour le second. APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi a affirm\u00e9, jeudi \u00e0 Oran, que le projet de r\u00e9alisation de la station de dessalement <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/07\/25\/le-projet-de-la-station-de-dessalement-de-leau-de-mer-de-cap-blanc-sera-livre-dans-les-delais-impartis\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":3743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[198],"tags":[],"class_list":["post-3742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/3742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=3742"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/3742\/revisions"}],"predecessor-version":[{"id":3744,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/3742\/revisions\/3744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/3743"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=3742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=3742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=3742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}