{"id":4792,"date":"2024-09-17T20:12:17","date_gmt":"2024-09-17T19:12:17","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=4792"},"modified":"2024-09-17T20:12:17","modified_gmt":"2024-09-17T19:12:17","slug":"le-president-tebboune-entame-un-second-mandat-en-annoncant-un-dialogue-politique-inclusif","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/09\/17\/le-president-tebboune-entame-un-second-mandat-en-annoncant-un-dialogue-politique-inclusif\/","title":{"rendered":"Le Pr\u00e9sident Tebboune entame un second mandat en annon\u00e7ant un dialogue politique inclusif"},"content":{"rendered":"<p><em>Le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, a officiellement entam\u00e9 hier son second mandat \u00e0 la magistrature supr\u00eame, apr\u00e8s avoir pr\u00eat\u00e9 serment au Palais des Nations \u00e0 Alger, apr\u00e8s sa r\u00e9\u00e9lection le 7 septembre avec 84,30% des voix. Dans un discours d&rsquo;investiture empreint d&rsquo;ambition et de renouveau, le pr\u00e9sident de la R\u00e9publique a d\u00e9voil\u00e9 sa vision pour l&rsquo;Alg\u00e9rie, mettant l&rsquo;accent sur un dialogue politique inclusif et une feuille de route \u00e9conomique et sociale ambitieuse.<\/em><\/p>\n<p>L&rsquo;annonce phare de cette journ\u00e9e d&rsquo;investiture fut sans conteste l&rsquo;engagement du Pr\u00e9sident Tebboune \u00e0 lancer un dialogue national ouvert. \u00ab\u00a0Au cours du second mandat, nous engagerons des discussions soutenues et des consultations avec l&rsquo;ensemble des forces vives du pays, politiques, \u00e9conomiques et juv\u00e9niles\u00a0\u00bb, a-t-il d\u00e9clar\u00e9. Un dialogue inclusif qui vise \u00e0 \u00ab\u00a0baliser ensemble le chemin qu&#8217;empruntera notre pays en mati\u00e8re de cons\u00e9cration de la v\u00e9ritable d\u00e9mocratie, non pas celle des slogans, mais celle qui donne la souverainet\u00e9 \u00e0 ceux qui la m\u00e9ritent\u00a0\u00bb. Cette initiative s&rsquo;inscrit dans une volont\u00e9 affirm\u00e9e de restaurer la confiance et de consolider les fondements d\u00e9mocratiques de l&rsquo;Alg\u00e9rie. Le Pr\u00e9sident a soulign\u00e9 l&rsquo;importance de ce dialogue pour surmonter les divisions du pass\u00e9 et construire un avenir commun. Il a notamment \u00e9voqu\u00e9 la n\u00e9cessit\u00e9 de r\u00e9concilier les diff\u00e9rentes composantes de la soci\u00e9t\u00e9 alg\u00e9rienne et de cr\u00e9er un espace de dialogue constructif.<br \/>\nDans un geste symbolique fort, imm\u00e9diatement apr\u00e8s la c\u00e9r\u00e9monie d&rsquo;investiture, le Pr\u00e9sident Tebboune a re\u00e7u ses adversaires de l&rsquo;\u00e9lection pr\u00e9sidentielle, M. Abdelaali Hassani Cherif du Mouvement de la soci\u00e9t\u00e9 pour la paix (MSP) et M. Youcef Aouchiche du Front des forces socialistes (FFS). Cette rencontre illustre la volont\u00e9 du pr\u00e9sident de tendre la main et d&rsquo;initier ce dialogue national sur des bases inclusives. Le pr\u00e9sident de la R\u00e9publique a aussi salu\u00e9 dans son discours le peuple alg\u00e9rien qui, a-t-il dit, \u00ab\u00a0a toujours prot\u00e9g\u00e9 par sa conscience nationale le processus de consolidation de la l\u00e9gitimit\u00e9 des institutions et d&rsquo;\u00e9dification de l&rsquo;\u00c9tat de droit \u00e0 travers les \u00e9ch\u00e9ances nationales constitutionnelles\u00a0\u00bb. Saluant, \u00e0 cette occasion, les candidats Abdelaali Hassani Cherif (Mouvement de la soci\u00e9t\u00e9 pour la paix) et Youcef Aouchiche (Front des forces socialistes), le pr\u00e9sident de la R\u00e9publique a dit : \u00ab Nous avons men\u00e9 ensemble une campagne \u00e9lectorale propre marqu\u00e9e par une concurrence loyale \u00e0 travers la pr\u00e9sentation des programmes et des id\u00e9es aux \u00e9lectrices et aux \u00e9lecteurs\u00a0\u00bb.<\/p>\n<p><strong>Un bilan sera pr\u00e9sent\u00e9 au Parlement<\/strong><\/p>\n<p>\u00ab\u00a0Si les m\u00e9thodes pour convaincre ont diff\u00e9r\u00e9, il n&rsquo;en demeure pas moins que la campagne \u00e9lectorale s&rsquo;est d\u00e9roul\u00e9e dans le respect mutuel, dans le cadre des r\u00e8gles de la pratique politique d\u00e9mocratique et conform\u00e9ment aux exigences de la conscience morale, de la fid\u00e9lit\u00e9 au pays des Chouhada et de la loyaut\u00e9 \u00e0 la patrie\u00a0\u00bb, a soutenu le pr\u00e9sident de la R\u00e9publique. Il a \u00e9galement salu\u00e9 avec fiert\u00e9 le \u00ab\u00a0succ\u00e8s de cette \u00e9ch\u00e9ance nationale importante marqu\u00e9e par la s\u00e9r\u00e9nit\u00e9 et la s\u00e9curit\u00e9 depuis le d\u00e9but de sa pr\u00e9paration, au lendemain de l&rsquo;annonce de la Pr\u00e9sidentielle anticip\u00e9e\u00a0\u00bb. Le pr\u00e9sident de la R\u00e9publique a, par l\u00e0 m\u00eame, salu\u00e9 l&rsquo;Arm\u00e9e nationale populaire (ANP), les corps de s\u00e9curit\u00e9, ainsi que tous les secteurs concern\u00e9s qui ont apport\u00e9 \u00ab\u00a0un appui logistique pour garantir une \u00e9lection transparente, libre et r\u00e9guli\u00e8re\u00a0\u00bb.<br \/>\nTebboune a \u00e9galement regrett\u00e9 la trahison pass\u00e9e et vertement critiqu\u00e9 les politiques \u00e9conomiques pass\u00e9es qui ont amen\u00e9 \u00e0 la d\u00e9sertification industrielle mettant en avant les r\u00e9alisations de son premier mandat pour rem\u00e9dier \u00e0 la situation il a cit\u00e9 dans ce sens les rapports du FMI et de la Banque mondiale qui mettent en avant le dynamisme de l&rsquo;\u00e9conomie alg\u00e9rienne qui affiche le taux de croissance le plus \u00e9lev\u00e9 de la r\u00e9gion. Il s&rsquo;est engag\u00e9 dans ce sens \u00e0 pr\u00e9senter le bilan de son premier mandat devant les deux chambres du Parlement avant fin 2024, ainsi que \u00ab\u00a0tous les d\u00e9tails\u00a0\u00bb relatifs au second mandat. Le pr\u00e9sident de la R\u00e9publique a pr\u00e9cis\u00e9 que, perp\u00e9tuant la \u00ab\u00a0bonne tradition\u00a0\u00bb qu&rsquo;il a institu\u00e9e, \u00ab\u00a0il prononcera, avant la fin de l&rsquo;ann\u00e9e, un discours \u00e0 la Nation devant les deux chambres du Parlement r\u00e9unies en session extraordinaire\u00a0\u00bb, lors duquel il pr\u00e9sentera \u00ab\u00a0tous les d\u00e9tails relatifs au second mandat, ainsi que le bilan \u00e9conomique et financier du premier mandat\u00a0\u00bb.<br \/>\nDans ce contexte, le Pr\u00e9sident Tebboune a pr\u00e9sent\u00e9 lors de son discours les grandes lignes d&rsquo;une feuille de route \u00e9conomique et sociale ambitieuse pour son second mandat, visant \u00e0 transformer en profondeur l&rsquo;\u00e9conomie nationale et \u00e0 am\u00e9liorer les conditions de vie des citoyens.<br \/>\n<strong><\/p>\n<p>Les priorit\u00e9s du second mandat<\/strong><\/p>\n<p>Le Pr\u00e9sident a fix\u00e9 des objectifs ambitieux en termes de croissance \u00e9conomique. Il vise notamment \u00e0 augmenter la contribution de l&rsquo;industrie au produit int\u00e9rieur brut (PIB) \u00e0 12% au cours de son mandat. Pour y parvenir, il mise sur une strat\u00e9gie de diversification \u00e9conomique et d&rsquo;encouragement de l&rsquo;investissement. Tebboune a annonc\u00e9 que pr\u00e8s de 9 000 projets d&rsquo;investissement ont d\u00e9j\u00e0 \u00e9t\u00e9 enregistr\u00e9s aupr\u00e8s de l&rsquo;Agence alg\u00e9rienne d&rsquo;investissement, avec l&rsquo;objectif ambitieux d&rsquo;atteindre 20 000 projets d&rsquo;ici la fin de son mandat en 2029. Cette dynamique d&rsquo;investissement devrait stimuler la croissance \u00e9conomique et cr\u00e9er de nombreux emplois.<br \/>\nL&rsquo;un des engagements phares du Pr\u00e9sident concerne l&rsquo;agriculture. Il s&rsquo;est engag\u00e9 \u00e0 assurer l&rsquo;autosuffisance agricole de l&rsquo;Alg\u00e9rie d&rsquo;ici \u00e0 2026, mettant en avant les progr\u00e8s d\u00e9j\u00e0 r\u00e9alis\u00e9s dans ce domaine. Tebboune a notamment annonc\u00e9 que le pays atteindra l&rsquo;autosuffisance en bl\u00e9 dur en 2025, et en orge et ma\u00efs en 2026. Pour y parvenir, il mise sur l&rsquo;\u00e9laboration d&rsquo;une carte agricole bas\u00e9e sur des crit\u00e8res scientifiques et sur des partenariats internationaux avec des pays leaders dans les fili\u00e8res strat\u00e9giques. Des projets dans ce sens sont d\u00e9j\u00e0 en cours. Il citera d&rsquo;ailleurs l&rsquo;exemple du partenariat avec le qatari Baladna, et celui avec les Italiens, alors que d&rsquo;autres sont en cours de discussion.<br \/>\nLe Pr\u00e9sident a \u00e9galement \u00e9voqu\u00e9 plusieurs grands projets d&rsquo;infrastructure visant \u00e0 moderniser le pays. Il a notamment annonc\u00e9 le lancement, en 2025, de grands barrages d&rsquo;interconnexion pour renforcer la gestion des ressources hydriques du pays. Ces projets s&rsquo;inscrivent dans une volont\u00e9 plus large de d\u00e9velopper les infrastructures du pays, notamment dans les domaines des transports, de l&rsquo;\u00e9nergie et des t\u00e9l\u00e9communications.<br \/>\nConscient des d\u00e9fis sociaux auxquels fait face l&rsquo;Alg\u00e9rie, le Pr\u00e9sident Tebboune s&rsquo;est engag\u00e9 \u00e0 prot\u00e9ger le pouvoir d&rsquo;achat des Alg\u00e9riens. Il a annonc\u00e9 une s\u00e9rie de mesures visant \u00e0 lutter contre l&rsquo;inflation, \u00e0 contr\u00f4ler les prix et \u00e0 augmenter les primes et les salaires. Ces mesures s&rsquo;inscrivent dans une politique plus large de protection sociale et de r\u00e9duction des in\u00e9galit\u00e9s. Le Pr\u00e9sident a r\u00e9affirm\u00e9 son engagement \u00e0 poursuivre la construction de deux millions de logements tous types confondus au cours de son mandat. Cette politique ambitieuse vise \u00e0 r\u00e9pondre \u00e0 la demande croissante de logements et \u00e0 am\u00e9liorer les conditions de vie des Alg\u00e9riens. Par ailleurs, Tebboune s&rsquo;est engag\u00e9 \u00e0 r\u00e9soudre d\u00e9finitivement le dossier des zones d&rsquo;ombre avant la fin de la premi\u00e8re ann\u00e9e de son mandat. Cette promesse t\u00e9moigne de sa volont\u00e9 de r\u00e9duire les disparit\u00e9s r\u00e9gionales et d&rsquo;am\u00e9liorer les conditions de vie dans les zones les plus d\u00e9favoris\u00e9es du pays.<br \/>\nIl a \u00e9voqu\u00e9 la n\u00e9cessit\u00e9 de poursuivre les r\u00e9formes dans les secteurs cl\u00e9s de la sant\u00e9 et de l&rsquo;\u00e9ducation pour assurer un d\u00e9veloppement durable et inclusif de l&rsquo;Alg\u00e9rie. Tebboune s&rsquo;est engag\u00e9 \u00e0 cr\u00e9er 450 000 emplois au cours de son mandat, en mettant particuli\u00e8rement l&rsquo;accent sur l&#8217;emploi des jeunes. Il a \u00e9galement annonc\u00e9 son ambition de porter le nombre de start-ups \u00e0 20 000, contre pr\u00e8s de 8 000 aujourd&rsquo;hui, soulignant ainsi l&rsquo;importance de l&rsquo;innovation et de l&rsquo;entrepreneuriat dans sa vision \u00e9conomique.<br \/>\nLe d\u00e9but du second mandat du Pr\u00e9sident Tebboune marque le d\u00e9but d&rsquo;un nouveau chapitre. En annon\u00e7ant un dialogue national inclusif et une feuille de route \u00e9conomique et sociale ambitieuse, le Pr\u00e9sident cherche \u00e0 rassembler les Alg\u00e9riens autour d&rsquo;un projet commun de d\u00e9veloppement et de d\u00e9mocratisation. Les d\u00e9fis sont nombreux, mais le Pr\u00e9sident semble d\u00e9termin\u00e9 \u00e0 les relever. La r\u00e9ussite de ce projet d\u00e9pendra de la capacit\u00e9 du gouvernement \u00e0 mettre en \u0153uvre ces ambitieuses promesses, mais aussi de la participation active de l&rsquo;ensemble des forces vives de la nation au dialogue annonc\u00e9. L&rsquo;Alg\u00e9rie entre ainsi dans une p\u00e9riode cruciale de son histoire, o\u00f9 la consolidation de la d\u00e9mocratie et le d\u00e9veloppement \u00e9conomique et social seront au c\u0153ur des priorit\u00e9s nationales.<br \/>\n<strong>Hocine Fadheli<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, a officiellement entam\u00e9 hier son second mandat \u00e0 la magistrature supr\u00eame, apr\u00e8s avoir pr\u00eat\u00e9 serment au Palais des <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/09\/17\/le-president-tebboune-entame-un-second-mandat-en-annoncant-un-dialogue-politique-inclusif\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":4793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[258,198],"tags":[],"class_list":["post-4792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-actualite"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/4792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=4792"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/4792\/revisions"}],"predecessor-version":[{"id":4794,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/4792\/revisions\/4794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/4793"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=4792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=4792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=4792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}