{"id":5096,"date":"2024-10-09T15:34:20","date_gmt":"2024-10-09T14:34:20","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=5096"},"modified":"2024-10-09T15:34:20","modified_gmt":"2024-10-09T14:34:20","slug":"onu-4e-commission-les-petitionnaires-defendent-le-droit-du-peuple-sahraoui-a-lautodetermination-les-etats-membres-de-lonu-sengagent-a-dessiner-un-avenir-meilleur-pour-lhuma","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/10\/09\/onu-4e-commission-les-petitionnaires-defendent-le-droit-du-peuple-sahraoui-a-lautodetermination-les-etats-membres-de-lonu-sengagent-a-dessiner-un-avenir-meilleur-pour-lhuma\/","title":{"rendered":"ONU\/4e commission: les p\u00e9titionnaires d\u00e9fendent le droit du peuple sahraoui \u00e0 l\u2019autod\u00e9termination Les Etats membres de l&rsquo;ONU s&rsquo;engagent \u00e0 dessiner un \u00abavenir meilleur\u00bb pour l&rsquo;humanit\u00e9"},"content":{"rendered":"<p>Le d\u00e9bat g\u00e9n\u00e9ral de la quatri\u00e8me Commission de l&rsquo;ONU, en charge des questions politiques sp\u00e9ciales et de la d\u00e9colonisation s&rsquo;est ouvert, ce mardi \u00e0 New York, au cours duquel un grand nombre de p\u00e9titionnaires, venus de diff\u00e9rentes r\u00e9gions du monde, ont plaid\u00e9 pour le droit l\u00e9gitime du peuple sahraoui \u00e0 l\u2019autod\u00e9termination et la fin de l&rsquo;occupation prolong\u00e9e du Sahara occidental par le Maroc.<\/p>\n<p>Le premier jour du d\u00e9bat a vu la participation de plusieurs personnalit\u00e9s telles que le repr\u00e9sentant du Front Polisario \u00e0 l\u2019ONU, Sidi Mohamed Omar, des repr\u00e9sentants du Parti communiste des Etats-Unis d\u2019Am\u00e9rique, de la Fondation colombienne pour l\u2019amiti\u00e9 avec le peuple sahraoui, de l\u2019Association \u00e9quatorienne pour l\u2019amiti\u00e9 avec le peuple sahraoui, de la Ligue internationale des juristes pour le Sahara occidental, de l\u2019Acad\u00e9mie alg\u00e9rienne de la jeunesse, du R\u00e9seau sahraoui de solidarit\u00e9 italienne avec le peuple sahraoui, et de l\u2019Universit\u00e9 de Santo Thomas.<\/p>\n<p>Les intervenants ont r\u00e9affirm\u00e9 le droit l\u00e9gitime du peuple sahraoui \u00e0 l\u2019autod\u00e9termination et soulign\u00e9 le statut juridique du Sahara occidental, qui reste un cas de d\u00e9colonisation inscrit sur la liste des territoires non autonomes des Nations Unies, en se basant sur diverses r\u00e9solutions pertinentes de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale et du Conseil de s\u00e9curit\u00e9 de l&rsquo;ONU, ainsi que celles des institutions judiciaires internationales.<\/p>\n<p>Ils ont rappel\u00e9, dans ce sens, la r\u00e9cente d\u00e9cision finale de la Cour de justice europ\u00e9enne (CJUE) sur le Sahara occidental ayant invalid\u00e9 les accords commerciaux entre l\u2019Union europ\u00e9enne (UE) et le Royaume du Maroc.<\/p>\n<p>Dans ce contexte, de nombreux interlocuteurs ont d\u00e9plor\u00e9 profond\u00e9ment la poursuite des violations des droits  l\u00e9gitimes du peuple sahraoui et du pillage continu de ses richesses, appelant la communaut\u00e9 internationale \u00e0 surveiller la situation des droits de l\u2019homme dans les territoires sahraouis occup\u00e9s en attendant la fin de l\u2019occupation de la derni\u00e8re colonie africaine et \u00e0 permettre au Sahara occidental, membre fondateur de l\u2019Union africaine (UA), d&rsquo;asseoir sa souverainet\u00e9 sur l&rsquo;ensemble du territoire national.<\/p>\n<p>Dans son allocution prononc\u00e9e lors des travaux de ce d\u00e9bat, Sidi Mohamed Omar a \u00e9voqu\u00e9 les arr\u00eats, rendus vendredi dernier, par la CJUE qui ont \u00abconfirm\u00e9 l\u2019ill\u00e9galit\u00e9 des accords entre l\u2019UE et la puissance occupante marocaine parce qu\u2019ils ont \u00e9t\u00e9 conclus en violation du droit du peuple sahraoui \u00e0 l\u2019autod\u00e9termination et \u00e0 la souverainet\u00e9 permanente sur ses ressources naturelles\u00bb.<\/p>\n<p>Pour le diplomate sahraoui, ce verdict constitue \u00abune victoire historique pour le peuple sahraoui et sa lutte l\u00e9gitime pour l\u2019autod\u00e9termination et l\u2019ind\u00e9pendance\u00bb. Il s\u2019agit aussi, a-t-il soulign\u00e9, d\u2019\u00bbune victoire de la justice et de l\u2019Etat de droit sur l\u2019injustice et la politique du pouvoir\u00bb.<\/p>\n<p>Il a, dans ce sens, appel\u00e9 les Etats membres de l\u2019UE et ses institutions \u00e0 \u00abrespecter pleinement le jugement de la CJUE\u00bb et \u00e0 s\u2019\u00bbabstenir de toute action, qui pourrait contribuer \u00e0 la consolidation de l\u2019occupation ill\u00e9gale du Sahara occidental par le Maroc\u00bb.<\/p>\n<p>Et de poursuivre: \u00abLe temps est venu pour voir le bon c\u00f4t\u00e9 de l\u2019histoire car les pays qui se respectent en Europe et ailleurs, qui sont vraiment engag\u00e9s \u00e0 respecter les principes du droit international, ne peuvent jamais accepter ou tol\u00e9rer la poursuite de l\u2019occupation ill\u00e9gale marocaine du Sahara occidental&#8230;\u00bb.<\/p>\n<p>Le repr\u00e9sentant du Front Polisario aupr\u00e8s de l&rsquo;ONU et coordinateur avec la MINURSO a, par ailleurs, \u00e9voqu\u00e9 la r\u00e9cente visite dans les territoires sahraouis de l&rsquo;Envoy\u00e9 personnel du Secr\u00e9taire g\u00e9n\u00e9ral des Nations Unies pour le Sahara occidental, M. Staffan de Mistura, dans le cadre de la poursuite de ses contacts avec les parties au conflit, le Front Polisario et la puissance occupante marocaine.<\/p>\n<p>Il a pr\u00e9cis\u00e9, \u00e0 cet effet, que le message transmis par le peuple sahraoui \u00e0 l\u2019\u00e9missaire des Nations unies \u00e9tait tr\u00e8s clair: \u00abNotre peuple, qui a fait tout ce qu\u2019il pouvait pour parvenir \u00e0 une paix juste et durable, poursuivra sa lutte de lib\u00e9ration par tous les moyens l\u00e9gitimes pour d\u00e9fendre son droit inali\u00e9nable \u00e0 l\u2019autod\u00e9termination et \u00e0 l\u2019ind\u00e9pendance\u00bb.<\/p>\n<p>Les travaux de la quatri\u00e8me commission de l&rsquo;ONU, en charge des questions politiques sp\u00e9ciales et de la d\u00e9colonisation se poursuivront jusqu\u2019\u00e0 lundi prochain, date \u00e0 laquelle le Comit\u00e9 continuera d\u2019entendre des p\u00e9titionnaires sur la d\u00e9colonisation du Sahara occidental ainsi que d\u2019autres territoires inscrits \u00e0 son ordre du jour. RA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9bat g\u00e9n\u00e9ral de la quatri\u00e8me Commission de l&rsquo;ONU, en charge des questions politiques sp\u00e9ciales et de la d\u00e9colonisation s&rsquo;est ouvert, ce mardi \u00e0 New <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/10\/09\/onu-4e-commission-les-petitionnaires-defendent-le-droit-du-peuple-sahraoui-a-lautodetermination-les-etats-membres-de-lonu-sengagent-a-dessiner-un-avenir-meilleur-pour-lhuma\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":5097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[202],"tags":[],"class_list":["post-5096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=5096"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5096\/revisions"}],"predecessor-version":[{"id":5098,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5096\/revisions\/5098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/5097"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=5096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=5096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=5096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}