{"id":5512,"date":"2024-11-11T15:40:49","date_gmt":"2024-11-11T14:40:49","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=5512"},"modified":"2024-11-11T15:40:49","modified_gmt":"2024-11-11T14:40:49","slug":"le-peuple-marocain-reaffirme-son-rejet-de-la-normalisation-et-denonce-laccostage-a-tanger-dun-navire-transportant-des-armes-pour-loccupant-sioniste","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2024\/11\/11\/le-peuple-marocain-reaffirme-son-rejet-de-la-normalisation-et-denonce-laccostage-a-tanger-dun-navire-transportant-des-armes-pour-loccupant-sioniste\/","title":{"rendered":"Le peuple marocain r\u00e9affirme son rejet de la normalisation et d\u00e9nonce l&rsquo;accostage \u00e0 Tanger d&rsquo;un navire transportant des armes pour l&rsquo;occupant sioniste"},"content":{"rendered":"<p>Le peuple marocain ne cesse de r\u00e9affirmer son soutien au peuple palestinien et son rejet de la normalisation entre le r\u00e9gime du Makhzen et l&rsquo;entit\u00e9 sioniste, d\u00e9non\u00e7ant ainsi l&rsquo;amarrage d&rsquo;un \u00ab\u00a0navire d&rsquo;armes\u00a0\u00bb sioniste dans le port de Tanger, consid\u00e9r\u00e9 par les protestataires comme \u00ab\u00a0une participation aux crimes de guerre sionistes\u00a0\u00bb commis dans la bande de Ghaza et au Liban, rapportent des m\u00e9dias marocains.<\/p>\n<p>Selon le site d&rsquo;information en ligne Aabbir, des citoyens marocains ont manifest\u00e9 dimanche devant le port m\u00e9diterran\u00e9en de Tanger, d\u00e9non\u00e7ant l&rsquo;accostage du \u00ab\u00a0navire d&rsquo;armes\u00a0\u00bb \u00e0 destination de l&rsquo;entit\u00e9 sioniste. Les manifestants ont brandi des slogans d\u00e9non\u00e7ant la r\u00e9ception de ce \u00ab\u00a0navire d&rsquo;armes\u00a0\u00bb \u00e0 destination de l&rsquo;entit\u00e9 sioniste. Ils ont affirm\u00e9 que les autorit\u00e9s marocaines l&rsquo;avaient autoris\u00e9 \u00e0 accoster dans le port, consid\u00e9rant cela comme \u00ab\u00a0une participation aux crimes de guerre commis (par l&rsquo;occupant sioniste) \u00e0 Ghaza et au Liban depuis plus d&rsquo;un an\u00a0\u00bb.<\/p>\n<p>Les participants \u00e0 la manifestation ont brandi les drapeaux palestinien et libanais, et scand\u00e9 des slogans tels que \u00ab\u00a0Ghaza vous l&rsquo;avez assi\u00e9g\u00e9e et le navire accept\u00e9\u00a0\u00bb.<\/p>\n<p>Outre des slogans contre cet accostage, les protestataires ont salu\u00e9 le refoulement du navire par les autorit\u00e9s espagnoles. A rappeler que, depuis sa reconnaissance au printemps dernier de l&rsquo;Etat palestinien, l&rsquo;Espagne refuse aux navires transportant une cargaison d&rsquo;armes \u00e0 destination de l&rsquo;entit\u00e9 sioniste l&rsquo;autorisation d&rsquo;accoster dans ses ports.<\/p>\n<p>Par ailleurs, les manifestants marocains ont renouvel\u00e9 leur soutien \u00e0 la r\u00e9sistance palestinienne et leur condamnation de l&rsquo;agression sioniste en cours contre le peuple palestinien notamment \u00e0 Ghaza depuis le 7 octobre 2023. Ils ont aussi exig\u00e9 \u00ab\u00a0la fin du g\u00e9nocide, la punition de l&rsquo;entit\u00e9 occupante pour ses crimes, la lev\u00e9e du si\u00e8ge de l&rsquo;enclave palestinienne et l&rsquo;entr\u00e9e de l&rsquo;aide dans ce territoire\u00a0\u00bb, tout en r\u00e9it\u00e9rant leur appel \u00e0 \u00ab\u00a0abandonner la normalisation\u00a0\u00bb.<\/p>\n<p>Cit\u00e9 par le site d&rsquo;information marocain en ligne Aabbir, le Mouvement de boycott de l&rsquo;entit\u00e9 sioniste, connu internationalement sous le nom de \u00ab\u00a0BDS\u00a0\u00bb (Boycott, d\u00e9sinvestissement et sanctions), d\u00e9nonce, lui aussi, la r\u00e9ception par le Maroc du \u00ab\u00a0navire d&rsquo;armes\u00a0\u00bb sioniste.<\/p>\n<p>Le BDS a d\u00e9clar\u00e9: \u00ab\u00a0Le Maroc a autoris\u00e9 un navire soup\u00e7onn\u00e9 de transporter des armes pour l&rsquo;occupation (sioniste) \u00e0 accoster dans le port de Tanger, apr\u00e8s que l&rsquo;Espagne ait refus\u00e9 de le recevoir\u00a0\u00bb. Il a pr\u00e9cis\u00e9, dans son rapport samedi dernier, que \u00ab\u00a0le navire +Maersk Denver+ fait partie de la flotte +Maersk+, qui est impliqu\u00e9e dans l&rsquo;exp\u00e9dition de fournitures militaires am\u00e9ricaines vers l&rsquo;entit\u00e9 sioniste, et qu&rsquo;il est donc raisonnablement soup\u00e7onn\u00e9 de transporter des cargaisons militaires ill\u00e9gales destin\u00e9es \u00e0 l&rsquo;occupant\u00a0\u00bb sioniste.<\/p>\n<p>Au moment o\u00f9 l&rsquo;occupant sioniste poursuit sans r\u00e9pit ses massacres contre la population de Ghaza faisant plus de 43.600 martyrs palestiniens, et aussi contre le Liban o\u00f9 le bilan d\u00e9passe les 3.000 martyrs, les appels \u00e0 mettre un terme \u00e0 l&rsquo;exportation des armes vers l&rsquo;entit\u00e9 sioniste ne cessent de se multiplier \u00e0 travers le monde.<\/p>\n<p>Le dernier appel en date remonte \u00e0 d\u00e9but novembre lorsque la Turquie a soumis \u00e0 l&rsquo;ONU une lettre conjointe, sign\u00e9e par 52 pays et deux organisations, demandant l&rsquo;arr\u00eat de la fourniture et de la livraison d&rsquo;armes \u00e0 l&rsquo;entit\u00e9 sioniste. RA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le peuple marocain ne cesse de r\u00e9affirmer son soutien au peuple palestinien et son rejet de la normalisation entre le r\u00e9gime du Makhzen et l&rsquo;entit\u00e9 <a href=\"https:\/\/capalgerie.dz\/index.php\/2024\/11\/11\/le-peuple-marocain-reaffirme-son-rejet-de-la-normalisation-et-denonce-laccostage-a-tanger-dun-navire-transportant-des-armes-pour-loccupant-sioniste\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":5513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[258,257],"tags":[],"class_list":["post-5512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-afrique"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=5512"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5512\/revisions"}],"predecessor-version":[{"id":5514,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5512\/revisions\/5514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/5513"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=5512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=5512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=5512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}