{"id":5873,"date":"2025-01-19T16:33:30","date_gmt":"2025-01-19T15:33:30","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=5873"},"modified":"2025-01-19T16:33:30","modified_gmt":"2025-01-19T15:33:30","slug":"textile-et-cuir-les-operateurs-appeles-a-sorganiser-en-clusters-pour-repondre-aux-besoins-du-marche-national","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2025\/01\/19\/textile-et-cuir-les-operateurs-appeles-a-sorganiser-en-clusters-pour-repondre-aux-besoins-du-marche-national\/","title":{"rendered":"Textile et cuir : les op\u00e9rateurs appel\u00e9s \u00e0 s&rsquo;organiser en clusters pour r\u00e9pondre aux besoins du march\u00e9 national"},"content":{"rendered":"<p>Le ministre de l&rsquo;Industrie et de la Production pharmaceutique, Sifi Ghrieb, a appel\u00e9 les op\u00e9rateurs \u00e9conomiques activant dans diverses fili\u00e8res industrielles, notamment dans les fili\u00e8res du cuir et du textile, \u00e0 s&rsquo;organiser en clusters pour participer \u00e0 la prise de d\u00e9cision en tant que force de proposition et contribuer \u00e0 l&rsquo;\u00e9laboration d&rsquo;une feuille de route pratique permettant de relancer ces deux fili\u00e8res, de r\u00e9pondre aux besoins locaux et d&rsquo;aller vers l&rsquo;exportation, indique samedi un communiqu\u00e9 du minist\u00e8re.<\/p>\n<p>Pr\u00e9sidant une rencontre regroupant les principaux op\u00e9rateurs \u00e9conomiques activant dans les fili\u00e8res du cuir et du textile, le ministre a mis l&rsquo;accent sur la n\u00e9cessit\u00e9 de \u00abconsolider l&rsquo;effort industriel national dans toutes les branches et fili\u00e8res industrielles dont les fili\u00e8res Cuir et Textile, et de structurer ces industries en clusters\u00bb, pr\u00e9cise le communiqu\u00e9.<\/p>\n<p>Ces clusters seront associ\u00e9s \u00e0 la \u00abprise de d\u00e9cision\u00bb, en identifiant tous les obstacles qui entravent le d\u00e9veloppement de ces deux fili\u00e8res et en proposant des solutions, selon M. Ghrieb qui a pr\u00e9cis\u00e9 que cela permettra de faire de ces groupements un canal de communication avec les autorit\u00e9s publiques.<\/p>\n<p>Aussi, a-t-il ajout\u00e9, l&rsquo;on attend de ces groupes qu&rsquo;ils soient une force de proposition \u00e0 m\u00eame de contribuer \u00e0 l&rsquo;\u00e9laboration d&rsquo;une feuille de route pratique pour relancer les industries du textile et du cuir et r\u00e9pondre aux besoins locaux en termes de quantit\u00e9, de qualit\u00e9 et \u00e0 des prix concurrentiels, tout en augmentant le taux d&rsquo;int\u00e9gration dans la cha\u00eene de valeur de ces fili\u00e8res et aller versl&rsquo;exportation.<\/p>\n<p>M. Ghrieb a \u00e9galement mis en avant l&rsquo;importance de la cr\u00e9ation de p\u00f4les d&rsquo;excellence pour les fili\u00e8res du cuir et du textile, de la coordination et de la coop\u00e9ration entre les diff\u00e9rents op\u00e9rateurs concernant la production, le marketing et le e-marketing.<\/p>\n<p> Afin de fournir une main d&rsquo;\u0153uvre qualifi\u00e9e, le ministre a annonc\u00e9 la cr\u00e9ation de plusieurs centres de formation sp\u00e9cialis\u00e9s dans les diff\u00e9rents m\u00e9tiers li\u00e9s aux fili\u00e8res du cuir et du textile r\u00e9partis \u00e0 travers l&rsquo;ensemble du territoire national, et ce en collaboration avec le secteur de l&rsquo;enseignement et de la formation professionnels, soulignant la n\u00e9cessit\u00e9 de pr\u00e9server les emplois.    <\/p>\n<p>Les participants \u00e0 cette rencontre \u00e0 laquelle ont pris part 70 op\u00e9rateurs \u00e9conomiques publics et priv\u00e9s, notamment des producteurs, sous-traitants, distributeurs et exportateurs de divers produits textiles et cuir, en sus de repr\u00e9sentants de groupes et d&rsquo;associations professionnels encadrant cette activit\u00e9, et d&rsquo;experts en la mati\u00e8re, ont \u00e9voqu\u00e9 les moyens et capacit\u00e9s dont disposent les producteurs locaux pour r\u00e9pondre aux besoins nationaux en mati\u00e8re de produits textiles et en cuir, notamment l&rsquo;habillement et la chaussure.<\/p>\n<p>Ils ont \u00e9galement \u00e9voqu\u00e9 les pr\u00e9occupations qui \u00abentravent le d\u00e9veloppement de ces fili\u00e8res en Alg\u00e9rie, telles que le manque de main-d&rsquo;\u0153uvre qualifi\u00e9e, les droits douaniers et les taxes fiscales appliqu\u00e9es sur la mati\u00e8re premi\u00e8re import\u00e9e, l&rsquo;absence de zones industrielles d\u00e9di\u00e9es aux fili\u00e8res du textile et du cuir, le manque de laboratoires sp\u00e9cialis\u00e9s pour le contr\u00f4le et la conformit\u00e9, n\u00e9cessaires aux op\u00e9rations d&rsquo;exportation, outre la probl\u00e9matique du march\u00e9 informel\u00bb, selon le communiqu\u00e9.  <\/p>\n<p>Cette rencontre s&rsquo;inscrit dans le cadre de l&rsquo;organisation et la relance des diff\u00e9rentes branches et fili\u00e8res industrielles selon \u00abune nouvelle vision\u00bb visant \u00e0 renforcer le dialogue franc et transparent entre les diff\u00e9rents acteurs des secteurs public et priv\u00e9, outre la mise en place d&rsquo;une approche commune \u00e0 m\u00eame de contribuer au d\u00e9veloppement du secteur industriel et \u00e0 la diversification de l&rsquo;\u00e9conomie nationale, selon la m\u00eame source. APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;Industrie et de la Production pharmaceutique, Sifi Ghrieb, a appel\u00e9 les op\u00e9rateurs \u00e9conomiques activant dans diverses fili\u00e8res industrielles, notamment dans les fili\u00e8res <a href=\"https:\/\/capalgerie.dz\/index.php\/2025\/01\/19\/textile-et-cuir-les-operateurs-appeles-a-sorganiser-en-clusters-pour-repondre-aux-besoins-du-marche-national\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":5874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[200],"tags":[],"class_list":["post-5873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=5873"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5873\/revisions"}],"predecessor-version":[{"id":5875,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/5873\/revisions\/5875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/5874"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=5873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=5873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=5873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}