{"id":6556,"date":"2026-03-28T12:51:25","date_gmt":"2026-03-28T11:51:25","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=6556"},"modified":"2026-03-28T12:51:25","modified_gmt":"2026-03-28T11:51:25","slug":"charge-par-le-president-de-la-republique-le-premier-ministre-preside-louverture-de-global-africa-tech-2026","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2026\/03\/28\/charge-par-le-president-de-la-republique-le-premier-ministre-preside-louverture-de-global-africa-tech-2026\/","title":{"rendered":"Charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, le Premier ministre pr\u00e9side l&rsquo;ouverture de Global Africa Tech 2026"},"content":{"rendered":"<p>Charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, le Premier ministre, M. Sifi Ghrieb, pr\u00e9side samedi au Centre international de conf\u00e9rences (CIC) Abdelatif-Rahal, \u00e0 Alger, la c\u00e9r\u00e9monie d&rsquo;ouverture de l&rsquo;\u00e9v\u00e8nement Global Africa Tech 2026.<\/p>\n<p>Organis\u00e9e par le minist\u00e8re de la Poste et des T\u00e9l\u00e9communications, sous le haut patronage du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, cette manifestation continentale d&rsquo;envergure accueillie par l&rsquo;Alg\u00e9rie du 28 au 30 mars courant sous le slogan \u00ab\u00a0Tous les r\u00e9seaux, une seule convergence\u00a0\u00bb, constitue \u00ab\u00a0une plateforme strat\u00e9gique de dialogue et de coop\u00e9ration, visant \u00e0 harmoniser les politiques publiques, les strat\u00e9gies d&rsquo;infrastructures, les dynamiques d&rsquo;investissement et les syst\u00e8mes d&rsquo;innovation, dans le cadre d&rsquo;une vision africaine unifi\u00e9e du num\u00e9rique\u00a0\u00bb.<\/p>\n<p>La c\u00e9r\u00e9monie d&rsquo;ouverture se d\u00e9roule en pr\u00e9sence \u00ab\u00a0du directeur de Cabinet \u00e0 la Pr\u00e9sidence de la R\u00e9publique, M. Boualem Boualem, du Conseiller aupr\u00e8s du pr\u00e9sident de la R\u00e9publique, charg\u00e9 de la Direction g\u00e9n\u00e9rale de la communication, M. Kamel Sidi Said, ainsi que de plusieurs membres du gouvernement, outre des d\u00e9l\u00e9gations officielles de haut niveau de plusieurs pays africains et de repr\u00e9sentants d&rsquo;institutions continentales et internationales\u00a0\u00bb.<\/p>\n<p>La premi\u00e8re \u00e9dition de cette manifestation enregistre \u00ab\u00a0une participation qualitative r\u00e9unissant les principaux op\u00e9rateurs de t\u00e9l\u00e9communications, des entreprises technologiques internationales et des investisseurs, en sus d&rsquo;un nombre d&rsquo;innovateurs et d&rsquo;experts du secteur num\u00e9rique, refl\u00e9tant ainsi l&rsquo;importance croissante de cet \u00e9v\u00e8nement aux niveaux r\u00e9gional et international\u00a0\u00bb.<\/p>\n<p>Cette rencontre incarne \u00ab\u00a0la vision strat\u00e9gique du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune\u00a0\u00bb, visant \u00e0 \u00ab\u00a0consolider la place de l&rsquo;Alg\u00e9rie en tant que hub de l&rsquo;innovation num\u00e9rique en Afrique, \u00e0 travers le soutien \u00e0 la transformation num\u00e9rique et le renforcement de l&rsquo;int\u00e9gration interafricaine\u00a0\u00bb.<\/p>\n<p>Il s&rsquo;agit \u00e9galement de \u00ab\u00a0construire un continent africain num\u00e9riquement interconnect\u00e9 \u00e0 travers l&rsquo;int\u00e9gration des r\u00e9seaux terrestres, maritimes, a\u00e9riens et spatiaux, garantissant ainsi une infrastructure moderne et s\u00e9curis\u00e9e r\u00e9pondant aux exigences de l&rsquo;\u00e8re num\u00e9rique\u00a0\u00bb.<\/p>\n<p>Cette manifestation vise \u00e9galement \u00e0 \u00ab\u00a0renforcer la souverainet\u00e9 num\u00e9rique et \u00e0 r\u00e9duire l&rsquo;\u00e9cart entre les pays africains, en d\u00e9veloppant des syst\u00e8mes de communication int\u00e9gr\u00e9s soutenant la croissance \u00e9conomique et accompagnant les transformations technologiques mondiales\u00a0\u00bb. APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, le Premier ministre, M. Sifi Ghrieb, pr\u00e9side samedi au Centre international de conf\u00e9rences (CIC) Abdelatif-Rahal, <a href=\"https:\/\/capalgerie.dz\/index.php\/2026\/03\/28\/charge-par-le-president-de-la-republique-le-premier-ministre-preside-louverture-de-global-africa-tech-2026\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":6557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[258,198],"tags":[],"class_list":["post-6556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-actualite"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/6556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=6556"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/6556\/revisions"}],"predecessor-version":[{"id":6558,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/6556\/revisions\/6558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/6557"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=6556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=6556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=6556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}