{"id":7040,"date":"2026-04-18T19:00:54","date_gmt":"2026-04-18T18:00:54","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=7040"},"modified":"2026-04-18T19:00:54","modified_gmt":"2026-04-18T18:00:54","slug":"steven-spielberg-presente-son-nouveau-film-sur-les-extraterrestres-disclosure-day","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2026\/04\/18\/steven-spielberg-presente-son-nouveau-film-sur-les-extraterrestres-disclosure-day\/","title":{"rendered":"Steven Spielberg pr\u00e9sente son nouveau film sur les extraterrestres \u00ab\u00a0Disclosure Day\u00a0\u00bb"},"content":{"rendered":"<p>Le c\u00e9l\u00e8bre r\u00e9alisateur am\u00e9ricain Steven Spielberg a offert mercredi un aper\u00e7u de son nouveau film \u00ab\u00a0Disclosure Day\u00a0\u00bb sur les extraterrestres, dont la sortie est pr\u00e9vue en juin prochain, 50 ans apr\u00e8s s&rsquo;\u00eatre empar\u00e9 pour la premi\u00e8re fois de ce th\u00e8me, ont rapport\u00e9 des m\u00e9dias.<\/p>\n<p>A 79 ans, Spielberg a pr\u00e9sent\u00e9 le film au CinemaCon de Las Vegas, salon des professionnels du cin\u00e9ma o\u00f9 les studios d\u00e9voilent leurs prochaines sorties aux exploitants de salles.<\/p>\n<p>Rappelant son film, \u00ab\u00a0Rencontres du troisi\u00e8me type\u00a0\u00bb (1977), \u00ab\u00a0Disclosure Day\u00a0\u00bb met en sc\u00e8ne la rencontre entre le genre humain et une vie extraterrestre, un sc\u00e9nario qui contient selon le r\u00e9alisateur, \u00ab\u00a0davantage de v\u00e9rit\u00e9 que de fiction\u00a0\u00bb.<\/p>\n<p>\u00ab\u00a0Disclosure Day\u00a0\u00bb, qui sortira le 12 juin aux Etats-Unis, met en vedette Emily Blunt, Josh O&rsquo;Connor, Eve Henson et Colman Domingo, entre autres.<\/p>\n<p>A l&rsquo;occasion du CinemaCon, le r\u00e9alisateur trois fois oscaris\u00e9 a re\u00e7u un prix de la Motion Picture Association, organisation interprofessionnelle am\u00e9ricaine qui repr\u00e9sente les int\u00e9r\u00eats des grands studios hollywoodiens.<\/p>\n<p>Steven Spielberg a \u00e9galement \u00e9voqu\u00e9 l&rsquo;importance \u00e0 ses yeux des longues dur\u00e9es de sortie des films en salle, alors que les plateformes de streaming continuent de rogner les recettes au box-office. APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le c\u00e9l\u00e8bre r\u00e9alisateur am\u00e9ricain Steven Spielberg a offert mercredi un aper\u00e7u de son nouveau film \u00ab\u00a0Disclosure Day\u00a0\u00bb sur les extraterrestres, dont la sortie est pr\u00e9vue <a href=\"https:\/\/capalgerie.dz\/index.php\/2026\/04\/18\/steven-spielberg-presente-son-nouveau-film-sur-les-extraterrestres-disclosure-day\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":7041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[207],"tags":[],"class_list":["post-7040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/7040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=7040"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/7040\/revisions"}],"predecessor-version":[{"id":7042,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/7040\/revisions\/7042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/7041"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=7040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=7040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=7040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}