{"id":7531,"date":"2026-05-12T15:53:20","date_gmt":"2026-05-12T14:53:20","guid":{"rendered":"https:\/\/capalgerie.dz\/?p=7531"},"modified":"2026-05-12T15:53:20","modified_gmt":"2026-05-12T14:53:20","slug":"le-president-angolais-salue-le-leadership-du-president-de-la-republique-dans-la-lutte-contre-le-terrorisme-et-lextremisme-en-afrique","status":"publish","type":"post","link":"https:\/\/capalgerie.dz\/index.php\/2026\/05\/12\/le-president-angolais-salue-le-leadership-du-president-de-la-republique-dans-la-lutte-contre-le-terrorisme-et-lextremisme-en-afrique\/","title":{"rendered":"Le pr\u00e9sident angolais salue le leadership du pr\u00e9sident de la R\u00e9publique dans la lutte contre le terrorisme et l&rsquo;extr\u00e9misme en Afrique"},"content":{"rendered":"<p>Le pr\u00e9sident de la R\u00e9publique d&rsquo;Angola, M. Joao Louren\u00e7o, a salu\u00e9, ce mardi \u00e0 Alger, le leadership du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, dans la lutte contre le terrorisme et toutes les formes d&rsquo;extr\u00e9misme sur le continent africain.<\/p>\n<p>Dans une allocution prononc\u00e9e lors de la session extraordinaire du Parlement, r\u00e9uni en ses deux chambres au Palais des Nations (Club des Pins), le pr\u00e9sident angolais a indiqu\u00e9 que le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, est \u00abdevenu le champion de l&rsquo;Union africaine dans le domaine de la lutte contre le terrorisme et l&rsquo;extr\u00e9misme\u00bb, soulignant que l&rsquo;Alg\u00e9rie \u00abd\u00e9ploie des efforts consid\u00e9rables, qu&rsquo;il convient de saluer, pour trouver des solutions aux probl\u00e8mes et aux d\u00e9fis auxquels est confront\u00e9 le continent\u00bb.<\/p>\n<p>L&rsquo;h\u00f4te de l&rsquo;Alg\u00e9rie a mis en garde contre le danger des organisations terroristes qui d\u00e9stabilisent les Etats, insistant sur la n\u00e9cessit\u00e9 d&rsquo;agir avec fermet\u00e9 pour \u00e9radiquer ce fl\u00e9au.<\/p>\n<p>Dans son discours, le Pr\u00e9sident Joao Louren\u00e7o a tenu \u00e0 r\u00e9affirmer la solidit\u00e9 des relations historiques unissant l&rsquo;Alg\u00e9rie et son pays, rappelant que \u00abgr\u00e2ce au soutien et \u00e0 l&rsquo;appui de l&rsquo;Alg\u00e9rie, l&rsquo;Angola est devenu un pays ind\u00e9pendant et souverain, conscient de l&rsquo;ampleur des d\u00e9fis qu&rsquo;il doit relever\u00bb.<\/p>\n<p>Il a \u00e9voqu\u00e9, dans ce sens, les d\u00e9funts Pr\u00e9sidents Ahmed Ben Bella et Houari Boumediene, qui, au-del\u00e0 de leur qualit\u00e9 de pr\u00e9sidents de l&rsquo;Alg\u00e9rie, \u00e9taient des \u00abpersonnalit\u00e9s de premier plan en Afrique\u00bb, a-t-il dit.<\/p>\n<p>Il a \u00e9galement pr\u00e9cis\u00e9 que l&rsquo;Alg\u00e9rie est \u00abun pays fr\u00e8re et un alli\u00e9 s\u00fbr et constant, avec lequel nous partageons toutes les valeurs qui constituent, depuis de longues ann\u00e9es, le socle des relations solides entre les deux pays\u00bb, soulignant la profondeur des liens qui les unissent, au regard des souffrances endur\u00e9es par les deux peuples sous le joug du colonialisme, qui a exploit\u00e9 les richesses du continent africain et marginalis\u00e9 la voix de ses peuples dans les instances internationales.<\/p>\n<p>Le pr\u00e9sident angolais a rappel\u00e9, \u00e0 ce titre, les massacres du 8 mai 1945 perp\u00e9tr\u00e9s par l&rsquo;occupant fran\u00e7ais en Alg\u00e9rie.<\/p>\n<p>Dans son discours, le Pr\u00e9sident Joao Louren\u00e7o a aussi mis en avant les positions communes des deux pays et leur convergence de vues sur plusieurs questions internationales et africaines, soulignant \u00abl&rsquo;importance de d\u00e9finir des priorit\u00e9s communes et de mettre en place des m\u00e9canismes de partenariat efficaces au service du d\u00e9veloppement et de la stabilit\u00e9 sur le continent\u00bb.<\/p>\n<p>Il a, par ailleurs, insist\u00e9 sur la n\u00e9cessit\u00e9 de pr\u00eater une attention particuli\u00e8re aux enjeux li\u00e9s au changement climatique et de renforcer la repr\u00e9sentation des pays africains au sein des organisations internationales, estimant que l&rsquo;Afrique \u00abdemeure convoit\u00e9e de l&rsquo;ext\u00e9rieur\u00bb, en raison de ses richesses et de ses ressources.<\/p>\n<p>\u00abLe continent doit s&rsquo;appuyer sur ses propres capacit\u00e9s et valoriser ses ressources au profit de ses peuples\u00bb, a-t-il soutenu.<\/p>\n<p>Apr\u00e8s avoir appel\u00e9 au rejet de toutes les formes de discrimination et d&rsquo;atteinte aux relations internationales fond\u00e9es sur le respect mutuel, le pr\u00e9sident angolais a mis en exergue la n\u00e9cessit\u00e9 de privil\u00e9gier les solutions diplomatiques et le dialogue pour mettre un terme aux conflits et aux guerres.<\/p>\n<p>Abordant le volet de la coop\u00e9ration bilat\u00e9rale sous ses divers aspects, le Pr\u00e9sident Joao Louren\u00e7o a indiqu\u00e9 que les relations entre l&rsquo;Alg\u00e9rie et l&rsquo;Angola \u00abpuisent leurs racines dans le pass\u00e9 commun et l&rsquo;\u00e9change d&rsquo;expertises\u00bb, rappelant, par l\u00e0 m\u00eame, la contribution de l&rsquo;Alg\u00e9rie \u00e0 la cr\u00e9ation de la compagnie nationale angolaise Sonangol, une collaboration qui a, a-t-il dit, constitu\u00e9 \u00abun pilier pour le renforcement du partenariat entre les deux pays et l&rsquo;exploitation des potentialit\u00e9s disponibles afin de b\u00e2tir un avenir fond\u00e9 sur les \u00e9changes et les int\u00e9r\u00eats mutuels, notamment \u00e0 travers le soutien aux infrastructures et la promotion du march\u00e9 commun africain\u00bb.<\/p>\n<p>Le pr\u00e9sident angolais a conclu son propos en saluant le soutien apport\u00e9 par l&rsquo;Alg\u00e9rie \u00e0 l&rsquo;Angola dans le domaine de l&rsquo;enseignement sup\u00e9rieur, \u00e0 travers l&rsquo;octroi de 8 000 bourses aux \u00e9tudiants angolais, affichant la forte volont\u00e9 de son pays de renforcer les relations de coop\u00e9ration bilat\u00e9rale \u00abau service des int\u00e9r\u00eats des deux peuples et de la promotion des valeurs de justice et de solidarit\u00e9 entre les Etats\u00bb. APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la R\u00e9publique d&rsquo;Angola, M. Joao Louren\u00e7o, a salu\u00e9, ce mardi \u00e0 Alger, le leadership du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, <a href=\"https:\/\/capalgerie.dz\/index.php\/2026\/05\/12\/le-president-angolais-salue-le-leadership-du-president-de-la-republique-dans-la-lutte-contre-le-terrorisme-et-lextremisme-en-afrique\/\" class=\"read-more-link\">Lire&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":7532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[258,198,257],"tags":[],"class_list":["post-7531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alaune","category-actualite","category-afrique"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/7531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/comments?post=7531"}],"version-history":[{"count":1,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/7531\/revisions"}],"predecessor-version":[{"id":7533,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/posts\/7531\/revisions\/7533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media\/7532"}],"wp:attachment":[{"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/media?parent=7531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/categories?post=7531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capalgerie.dz\/index.php\/wp-json\/wp\/v2\/tags?post=7531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}